{"id":7588,"date":"2025-06-28T19:21:45","date_gmt":"2025-06-28T19:21:45","guid":{"rendered":"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/"},"modified":"2025-06-29T05:05:35","modified_gmt":"2025-06-29T05:05:35","slug":"challenges-for-midwives-pregnant-women-and-illicit-drug-use","status":"publish","type":"post","link":"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/","title":{"rendered":"Challenges for midwives: pregnant women and illicit drug use"},"content":{"rendered":"<p>This article was originally published as: <strong>Challenges for midwives: pregnant women and illicit drug use<\/strong><\/p>\n<p>Original Article Link: <a href='https:\/\/www.ajan.com.au\/index.php\/AJAN\/article\/view\/1697' target='_blank' rel='noopener'>Read Original Article<\/a><\/p>\n<p>Download PDF: <a href='https:\/\/www.ajan.com.au\/index.php\/AJAN\/article\/download\/1697\/429' target='_blank' rel='noopener'>Click Here to Download PDF<\/a><\/p>\n<h2>Abstract<\/h2>\n<p>Objective: The purpose of the paper is to introduce illicit drug use as a societal problem and describes the response of the Australian Government. Specifically the paper examines the use of illicit drugs by pregnant women and the role of midwives in supporting these women throughout pregnancy and birth.<br \/>\nSetting: Maternity services, specifically antenatal care clinics.<br \/>\nConclusion: In Australia the rate of pregnant women who use illicit drugs is escalating. These pregnancies are high obstetric risk with potential for harm to both the mother and the baby. Pregnancy however is seen as \u2018window of opportunity\u2019; a time to provide education, choices and support. The literature describes that for health professionals working with pregnant women who are illicit drug users is challenging and for some health professionals their interaction can be negative. Australia advocates harm minimisation and encourages harm reduction strategies. Midwives are in a position to implement these strategies within the maternity setting. Further research is recommended as well as professional development programs for midwives to upgrade knowledge and cultivate engagement skills to enable appropriate and positive interaction with pregnant women who use illicit drugs.<\/p>\n<h2>Authors<\/h2>\n<ul>\n<li>Maureen Miles<\/li>\n<li>Karen Francis<\/li>\n<li>Ysanne Chapman<\/li>\n<\/ul>\n<h2>Keywords<\/h2>\n<p>illicit drugs, pregnant, midwives, antenatal care<\/p>\n<h2>References<\/h2>\n<p>References not available for this article.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>This article was originally published as: Challenges for midwives: pregnant women and illicit drug use Original Article Link: Read Original&#8230;<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[124],"tags":[4886,4864,4129,4885],"class_list":["post-7588","post","type-post","status-publish","format-standard","hentry","category-articles","tag-antenatal-care","tag-illicit-drugs","tag-midwives","tag-pregnant","wpcat-124-id"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Challenges for midwives: pregnant women and illicit drug use - IJSSASS Repository<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Challenges for midwives: pregnant women and illicit drug use - IJSSASS Repository\" \/>\n<meta property=\"og:description\" content=\"This article was originally published as: Challenges for midwives: pregnant women and illicit drug use Original Article Link: Read Original...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/\" \/>\n<meta property=\"og:site_name\" content=\"IJSSASS Repository\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijssass\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-28T19:21:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-29T05:05:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ijssass.com\/journal\/wp-content\/uploads\/2023\/07\/c-users-user-desktop-logo-pnglogo-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"195\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/ijssass.com\/journal\/#\/schema\/person\/adf9bae5731958270e2140cfc1af3771\"},\"headline\":\"Challenges for midwives: pregnant women and illicit drug use\",\"datePublished\":\"2025-06-28T19:21:45+00:00\",\"dateModified\":\"2025-06-29T05:05:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/\"},\"wordCount\":244,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ijssass.com\/journal\/#organization\"},\"keywords\":[\"antenatal care\",\"illicit drugs\",\"midwives\",\"pregnant\"],\"articleSection\":[\"Articles\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/\",\"url\":\"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/\",\"name\":\"Challenges for midwives: pregnant women and illicit drug use - IJSSASS Repository\",\"isPartOf\":{\"@id\":\"https:\/\/ijssass.com\/journal\/#website\"},\"datePublished\":\"2025-06-28T19:21:45+00:00\",\"dateModified\":\"2025-06-29T05:05:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ijssass.com\/journal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Challenges for midwives: pregnant women and illicit drug use\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ijssass.com\/journal\/#website\",\"url\":\"https:\/\/ijssass.com\/journal\/\",\"name\":\"INTERNATIONAL JOURNAL OF SOCIAL SCIENCES AND SCIENTIFIC STUDIES\",\"description\":\"Open Access Library\",\"publisher\":{\"@id\":\"https:\/\/ijssass.com\/journal\/#organization\"},\"alternateName\":\"IJSSASS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ijssass.com\/journal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ijssass.com\/journal\/#organization\",\"name\":\"INTERNATIONAL JOURNAL OF SOCIAL SCIENCES AND SCIENTIFIC STUDIES\",\"alternateName\":\"IJSSASS\",\"url\":\"https:\/\/ijssass.com\/journal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ijssass.com\/journal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ijssass.com\/journal\/wp-content\/uploads\/2023\/07\/c-users-user-desktop-logo-pnglogo-3.png\",\"contentUrl\":\"https:\/\/ijssass.com\/journal\/wp-content\/uploads\/2023\/07\/c-users-user-desktop-logo-pnglogo-3.png\",\"width\":300,\"height\":195,\"caption\":\"INTERNATIONAL JOURNAL OF SOCIAL SCIENCES AND SCIENTIFIC STUDIES\"},\"image\":{\"@id\":\"https:\/\/ijssass.com\/journal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ijssass\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/ijssass.com\/journal\/#\/schema\/person\/adf9bae5731958270e2140cfc1af3771\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ijssass.com\/journal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e2404e10f252fd74bce698fdfc0296b3cfb701b99d14951364bf9586aaa0c4a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e2404e10f252fd74bce698fdfc0296b3cfb701b99d14951364bf9586aaa0c4a8?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/ijssass.com\/journal\"],\"url\":\"https:\/\/ijssass.com\/journal\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Challenges for midwives: pregnant women and illicit drug use - IJSSASS Repository","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/","og_locale":"en_US","og_type":"article","og_title":"Challenges for midwives: pregnant women and illicit drug use - IJSSASS Repository","og_description":"This article was originally published as: Challenges for midwives: pregnant women and illicit drug use Original Article Link: Read Original...","og_url":"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/","og_site_name":"IJSSASS Repository","article_publisher":"https:\/\/www.facebook.com\/ijssass","article_published_time":"2025-06-28T19:21:45+00:00","article_modified_time":"2025-06-29T05:05:35+00:00","og_image":[{"width":300,"height":195,"url":"https:\/\/ijssass.com\/journal\/wp-content\/uploads\/2023\/07\/c-users-user-desktop-logo-pnglogo-2.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/#article","isPartOf":{"@id":"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/"},"author":{"name":"admin","@id":"https:\/\/ijssass.com\/journal\/#\/schema\/person\/adf9bae5731958270e2140cfc1af3771"},"headline":"Challenges for midwives: pregnant women and illicit drug use","datePublished":"2025-06-28T19:21:45+00:00","dateModified":"2025-06-29T05:05:35+00:00","mainEntityOfPage":{"@id":"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/"},"wordCount":244,"commentCount":0,"publisher":{"@id":"https:\/\/ijssass.com\/journal\/#organization"},"keywords":["antenatal care","illicit drugs","midwives","pregnant"],"articleSection":["Articles"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/","url":"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/","name":"Challenges for midwives: pregnant women and illicit drug use - IJSSASS Repository","isPartOf":{"@id":"https:\/\/ijssass.com\/journal\/#website"},"datePublished":"2025-06-28T19:21:45+00:00","dateModified":"2025-06-29T05:05:35+00:00","breadcrumb":{"@id":"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ijssass.com\/journal\/challenges-for-midwives-pregnant-women-and-illicit-drug-use\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ijssass.com\/journal\/"},{"@type":"ListItem","position":2,"name":"Challenges for midwives: pregnant women and illicit drug use"}]},{"@type":"WebSite","@id":"https:\/\/ijssass.com\/journal\/#website","url":"https:\/\/ijssass.com\/journal\/","name":"INTERNATIONAL JOURNAL OF SOCIAL SCIENCES AND SCIENTIFIC STUDIES","description":"Open Access Library","publisher":{"@id":"https:\/\/ijssass.com\/journal\/#organization"},"alternateName":"IJSSASS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ijssass.com\/journal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ijssass.com\/journal\/#organization","name":"INTERNATIONAL JOURNAL OF SOCIAL SCIENCES AND SCIENTIFIC STUDIES","alternateName":"IJSSASS","url":"https:\/\/ijssass.com\/journal\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ijssass.com\/journal\/#\/schema\/logo\/image\/","url":"https:\/\/ijssass.com\/journal\/wp-content\/uploads\/2023\/07\/c-users-user-desktop-logo-pnglogo-3.png","contentUrl":"https:\/\/ijssass.com\/journal\/wp-content\/uploads\/2023\/07\/c-users-user-desktop-logo-pnglogo-3.png","width":300,"height":195,"caption":"INTERNATIONAL JOURNAL OF SOCIAL SCIENCES AND SCIENTIFIC STUDIES"},"image":{"@id":"https:\/\/ijssass.com\/journal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijssass"]},{"@type":"Person","@id":"https:\/\/ijssass.com\/journal\/#\/schema\/person\/adf9bae5731958270e2140cfc1af3771","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ijssass.com\/journal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e2404e10f252fd74bce698fdfc0296b3cfb701b99d14951364bf9586aaa0c4a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e2404e10f252fd74bce698fdfc0296b3cfb701b99d14951364bf9586aaa0c4a8?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/ijssass.com\/journal"],"url":"https:\/\/ijssass.com\/journal\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/ijssass.com\/journal\/wp-json\/wp\/v2\/posts\/7588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ijssass.com\/journal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ijssass.com\/journal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ijssass.com\/journal\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/ijssass.com\/journal\/wp-json\/wp\/v2\/comments?post=7588"}],"version-history":[{"count":1,"href":"https:\/\/ijssass.com\/journal\/wp-json\/wp\/v2\/posts\/7588\/revisions"}],"predecessor-version":[{"id":7635,"href":"https:\/\/ijssass.com\/journal\/wp-json\/wp\/v2\/posts\/7588\/revisions\/7635"}],"wp:attachment":[{"href":"https:\/\/ijssass.com\/journal\/wp-json\/wp\/v2\/media?parent=7588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ijssass.com\/journal\/wp-json\/wp\/v2\/categories?post=7588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ijssass.com\/journal\/wp-json\/wp\/v2\/tags?post=7588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}